{"id":521,"date":"2025-11-14T11:14:51","date_gmt":"2025-11-14T10:14:51","guid":{"rendered":"https:\/\/juwelier-kuhl.de\/?p=521"},"modified":"2026-03-04T15:16:16","modified_gmt":"2026-03-04T14:16:16","slug":"unsere-regelmaessig-stattfindenden-trauringmessen","status":"publish","type":"post","link":"https:\/\/www.juwelier-kuhl.de\/index.php\/2025\/11\/14\/unsere-regelmaessig-stattfindenden-trauringmessen\/","title":{"rendered":"Unsere regelm\u00e4\u00dfig stattfindenden Trauringmessen"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<figure class=\"wp-block-image size-thumbnail is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/juwelier-kuhl.de\/wp-content\/uploads\/2025\/04\/Favicon512x512-150x150.jpg\" alt=\"\" class=\"wp-image-12\" style=\"width:auto;height:50px\" srcset=\"https:\/\/www.juwelier-kuhl.de\/wp-content\/uploads\/2025\/04\/Favicon512x512-150x150.jpg 150w, https:\/\/www.juwelier-kuhl.de\/wp-content\/uploads\/2025\/04\/Favicon512x512-300x300.jpg 300w, https:\/\/www.juwelier-kuhl.de\/wp-content\/uploads\/2025\/04\/Favicon512x512.jpg 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure>\n\n\n\n<div  class=\"tribe-compatibility-container\" >\n\t<div\n\t\t class=\"tribe-common tribe-events tribe-events-view tribe-events-view--widget-events-list tribe-events-widget\" \t\tdata-js=\"tribe-events-view\"\n\t\tdata-view-rest-url=\"https:\/\/www.juwelier-kuhl.de\/index.php\/wp-json\/tribe\/views\/v2\/html\"\n\t\tdata-view-manage-url=\"1\"\n\t\t\t\t\t\t\tdata-view-breakpoint-pointer=\"3a0b8820-e016-4adf-8484-5fdb202160bb\"\n\t\t\t>\n\t\t<div class=\"tribe-events-widget-events-list\">\n\n\t\t\t<script type=\"application\/ld+json\">\r\n[{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Trauring-Hausmesse Juni\",\"description\":\"\",\"url\":\"https:\/\/www.juwelier-kuhl.de\/index.php\/event\/trauring-hausmesse-8\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-06-12T10:00:00+02:00\",\"endDate\":\"2026-06-12T18:00:00+02:00\",\"performer\":\"Organization\"}]\r\n<\/script>\n\t\t\t<script data-js=\"tribe-events-view-data\" type=\"application\/json\">\n\t{\"slug\":\"widget-events-list\",\"prev_url\":\"\",\"next_url\":\"\",\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Widgets\\\\Widget_List_View\",\"view_slug\":\"widget-events-list\",\"view_label\":\"View\",\"view\":null,\"should_manage_url\":true,\"id\":null,\"alias-slugs\":null,\"title\":\"Veranstaltungen von Mai 13 \\u2013 Juni 12 \\u2013 Juwelier Kuhl Velten\",\"limit\":\"5\",\"no_upcoming_events\":true,\"featured_events_only\":false,\"jsonld_enable\":true,\"tribe_is_list_widget\":false,\"admin_fields\":{\"title\":{\"label\":\"Titel:\",\"type\":\"text\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-title\",\"name\":\"widget-tribe-widget-events-list[-1][title]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"limit\":{\"label\":\"Anzeige:\",\"type\":\"number\",\"default\":5,\"min\":1,\"max\":10,\"step\":1,\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-limit\",\"name\":\"widget-tribe-widget-events-list[-1][limit]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"no_upcoming_events\":{\"label\":\"Blenden Sie dieses Widget aus, wenn es keine bevorstehenden Veranstaltungen gibt.\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-no_upcoming_events\",\"name\":\"widget-tribe-widget-events-list[-1][no_upcoming_events]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"featured_events_only\":{\"label\":\"Nur auf hervorgehobene Veranstaltungen beschr\\u00e4nken\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-featured_events_only\",\"name\":\"widget-tribe-widget-events-list[-1][featured_events_only]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"jsonld_enable\":{\"label\":\"JSON-LD-Daten generieren\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-jsonld_enable\",\"name\":\"widget-tribe-widget-events-list[-1][jsonld_enable]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"events\":[571],\"url\":\"https:\\\/\\\/www.juwelier-kuhl.de\\\/?post_type=tribe_events&eventDisplay=widget-events-list\",\"url_event_date\":false,\"bar\":{\"keyword\":\"\",\"date\":\"\"},\"today\":\"2026-05-13 00:00:00\",\"now\":\"2026-05-13 14:18:52\",\"home_url\":\"https:\\\/\\\/www.juwelier-kuhl.de\",\"rest_url\":\"https:\\\/\\\/www.juwelier-kuhl.de\\\/index.php\\\/wp-json\\\/tribe\\\/views\\\/v2\\\/html\",\"rest_method\":\"GET\",\"rest_nonce\":\"\",\"today_url\":\"https:\\\/\\\/www.juwelier-kuhl.de\\\/?post_type=tribe_events&eventDisplay=widget-events-list&rest_route=%2Fwp%2Fv2%2Fposts%2F521\",\"today_title\":\"Heutiges Datum ausw\\u00e4hlen\",\"today_label\":\"Heute\",\"prev_label\":\"\",\"next_label\":\"\",\"date_formats\":{\"compact\":\"n\\\/j\\\/Y\",\"month_and_year_compact\":\"n\\\/j\\\/Y\",\"month_and_year\":\"F Y\",\"time_range_separator\":\" - \",\"date_time_separator\":\" @ \"},\"messages\":[],\"start_of_week\":\"1\",\"header_title\":\"\",\"header_title_element\":\"h1\",\"content_title\":\"\",\"show_content_title\":false,\"breadcrumbs\":[],\"backlink\":false,\"before_events\":\"\",\"after_events\":\"\\n<!--\\nThis calendar is powered by The Events Calendar.\\nhttp:\\\/\\\/evnt.is\\\/18wn\\n-->\\n\",\"display_events_bar\":false,\"disable_event_search\":false,\"live_refresh\":true,\"ical\":{\"display_link\":true,\"link\":{\"url\":\"https:\\\/\\\/www.juwelier-kuhl.de\\\/?post_type=tribe_events&#038;eventDisplay=widget-events-list&#038;ical=1\",\"text\":\"Veranstaltungen als iCal exportieren\",\"title\":\"Diese Funktion verwenden, um Kalenderdaten mit Google Kalender, Apple iCal und kompatiblen Apps zu teilen\"}},\"container_classes\":[\"tribe-common\",\"tribe-events\",\"tribe-events-view\",\"tribe-events-view--widget-events-list\",\"tribe-events-widget\"],\"container_data\":[],\"is_past\":false,\"breakpoints\":{\"xsmall\":500,\"medium\":768,\"full\":960},\"breakpoint_pointer\":\"3a0b8820-e016-4adf-8484-5fdb202160bb\",\"is_initial_load\":false,\"public_views\":{\"list\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\List_View\",\"view_url\":\"https:\\\/\\\/www.juwelier-kuhl.de\\\/events\\\/liste\\\/\",\"view_label\":\"Liste\",\"aria_label\":\"Zeige Veranstaltungen in der Liste Ansicht\"},\"month\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Month_View\",\"view_url\":\"https:\\\/\\\/www.juwelier-kuhl.de\\\/events\\\/monat\\\/\",\"view_label\":\"Monat\",\"aria_label\":\"Zeige Veranstaltungen in der Monat Ansicht\"}},\"show_latest_past\":false,\"past\":false,\"compatibility_classes\":[\"tribe-compatibility-container\"],\"view_more_text\":\"Kalender anzeigen\",\"view_more_title\":\"Weitere anzeigen Veranstaltungen.\",\"view_more_link\":\"https:\\\/\\\/www.juwelier-kuhl.de\\\/events\\\/\",\"widget_title\":\"Bevorstehende Veranstaltungen\",\"hide_if_no_upcoming_events\":true,\"display\":[],\"subscribe_links\":{\"gcal\":{\"label\":\"Google Kalender\",\"single_label\":\"Zum Google Kalender hinzuf\\u00fcgen\",\"visible\":true,\"block_slug\":\"hasGoogleCalendar\"},\"ical\":{\"label\":\"iCalendar\",\"single_label\":\"Zu iCalendar hinzuf\\u00fcgen\",\"visible\":true,\"block_slug\":\"hasiCal\"},\"outlook-365\":{\"label\":\"Outlook 365\",\"single_label\":\"Outlook 365\",\"visible\":true,\"block_slug\":\"hasOutlook365\"},\"outlook-live\":{\"label\":\"Outlook Live\",\"single_label\":\"Outlook Live\",\"visible\":true,\"block_slug\":\"hasOutlookLive\"},\"ics\":{\"label\":\".ics Datei exportieren\",\"single_label\":\".ics Datei exportieren\",\"visible\":true,\"block_slug\":null},\"outlook-ics\":{\"label\":\"Exportiere Outlook .ics Datei\",\"single_label\":\"Exportiere Outlook .ics Datei\",\"visible\":true,\"block_slug\":null}},\"_context\":{\"slug\":\"widget-events-list\"}}<\/script>\n\n\t\t\t\t\t\t\t<header class=\"tribe-events-widget-events-list__header\">\n\t\t\t\t\t<h2 class=\"tribe-events-widget-events-list__header-title tribe-common-h6 tribe-common-h--alt\">\n\t\t\t\t\t\tBevorstehende Veranstaltungen\t\t\t\t\t<\/h2>\n\t\t\t\t<\/header>\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"tribe-events-widget-events-list__events\">\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-06-12\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tJuni\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t12\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-571 tribe_events type-tribe_events status-publish hentry\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-06-12\">\n\t\t<span class=\"tribe-event-date-start\">10:00<\/span> &#8211; <span class=\"tribe-event-time\">18:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a\n\t\thref=\"https:\/\/www.juwelier-kuhl.de\/index.php\/event\/trauring-hausmesse-8\/\"\n\t\ttitle=\"Trauring-Hausmesse Juni\"\n\t\trel=\"bookmark\"\n\t\tclass=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\"\n\t>\n\t\tTrauring-Hausmesse Juni\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"tribe-events-widget-events-list__view-more tribe-common-b1 tribe-common-b2--min-medium\">\n\t<a\n\t\thref=\"https:\/\/www.juwelier-kuhl.de\/events\/\"\n\t\tclass=\"tribe-events-widget-events-list__view-more-link tribe-common-anchor-thin\"\n\t\ttitle=\"Weitere anzeigen Veranstaltungen.\"\n\t>\n\t\tKalender anzeigen\t<\/a>\n<\/div>\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<script data-js='tribe-events-view-nonce-data' type='application\/json'>{\"tvn1\":\"65f182e7be\",\"tvn2\":\"\"}<\/script>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":523,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.juwelier-kuhl.de\/index.php\/wp-json\/wp\/v2\/posts\/521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.juwelier-kuhl.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.juwelier-kuhl.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.juwelier-kuhl.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.juwelier-kuhl.de\/index.php\/wp-json\/wp\/v2\/comments?post=521"}],"version-history":[{"count":6,"href":"https:\/\/www.juwelier-kuhl.de\/index.php\/wp-json\/wp\/v2\/posts\/521\/revisions"}],"predecessor-version":[{"id":536,"href":"https:\/\/www.juwelier-kuhl.de\/index.php\/wp-json\/wp\/v2\/posts\/521\/revisions\/536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.juwelier-kuhl.de\/index.php\/wp-json\/wp\/v2\/media\/523"}],"wp:attachment":[{"href":"https:\/\/www.juwelier-kuhl.de\/index.php\/wp-json\/wp\/v2\/media?parent=521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.juwelier-kuhl.de\/index.php\/wp-json\/wp\/v2\/categories?post=521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.juwelier-kuhl.de\/index.php\/wp-json\/wp\/v2\/tags?post=521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}